{"id":3098,"date":"2018-03-03T18:16:30","date_gmt":"2018-03-03T17:16:30","guid":{"rendered":"http:\/\/marolles.brussels\/2017\/12\/03\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/"},"modified":"2018-08-10T18:12:33","modified_gmt":"2018-08-10T16:12:33","slug":"2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute","status":"publish","type":"post","link":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/","title":{"rendered":"2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute&#8230;"},"content":{"rendered":"<p>MEUBLIA, une institution du quartier a \u00e9t\u00e9 d\u00e9finitivement ferm\u00e9, en f\u00e9vrier 2017, apr\u00e8s plus de 50 ans d\u2019existence. D&#8217;une ancienne distillerie du XIXe devenue une salle de danse au d\u00e9but du XXe si\u00e8cle, Meublia avait r\u00e9alis\u00e9 une vaste salle d&#8217;exposition enti\u00e8rement consacr\u00e9e au confort de la maison.<br \/>\nCette institution s\u2019identifiait, en partie, \u00e0 l\u2019association de commer\u00e7ants, Raymond Halconruy, c\u2019\u00e9tait Monsieur Meublia, celui des g\u00e9ants, pour ceux-l\u00e0 du quartier&#8230;<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-3098 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/2017-dem-fevier-1-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-f\u00e9vier-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3422\" srcset=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-f\u00e9vier-1-150x150.jpg 150w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-f\u00e9vier-1-63x63.jpg 63w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-3422'>\n\t\t\t\tD\u00e9p\u00f4t chez MEUBLIA\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/2017-dem-fevier-0-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-f\u00e9vier-0-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3420\" srcset=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-f\u00e9vier-0-150x150.jpg 150w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-f\u00e9vier-0-63x63.jpg 63w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-3420'>\n\t\t\t\tEn route vers l&#8217;\u00e9glise\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/2017-dem-fevier-6-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-f\u00e9vier-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3432\" srcset=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-f\u00e9vier-6-150x150.jpg 150w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-f\u00e9vier-6-63x63.jpg 63w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-3432'>\n\t\t\t\tDona Brabantia \u00e0 l&#8217;\u00e9glise\n\t\t\t\t<\/dd><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Plus de 300 m2 r\u00e9partis en diff\u00e9rents endroits permettaient \u00e0 l\u2019association de stocker g\u00e9ants, archives, illuminations, chalets, tentes, \u00e9choppes, chariots d\u2019arrosage, \u00e9chelles, terreau, drapeaux, objets divers et vari\u00e9s accumul\u00e9s par l\u2019association au cours des 30 derni\u00e8res ann\u00e9es.<br \/>\nNous avons, donc, d\u00fb chercher des lieux pour d\u00e9m\u00e9nager et stocker tous cela, dans l\u2019urgence, nos appels \u00e0 l\u2019aide ont \u00e9t\u00e9 entendus\u00a0!<br \/>\nL\u2019institut Diderot nous a donn\u00e9 un grand coup de main, ainsi que nos ALE, deux porteurs de petits g\u00e9ants, Dimitri du CCBruegel, Les Mignonnettes du Quartier Bruegel, Les Ateliers Populaires et la Maison de Jeunes le 88.<br \/>\nMerci aux Copains du p\u2019tit Bitume qui nous donnent les coups de mains n\u00e9cessaires dans l\u2019urgence\u00a0!<\/p>\n\n\t\t<style>\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-3098 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/17-04-20-demenagement-7-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-04-20-d\u00e9m\u00e9nagement-7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-3392\" srcset=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-04-20-d\u00e9m\u00e9nagement-7-150x150.jpg 150w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-04-20-d\u00e9m\u00e9nagement-7-63x63.jpg 63w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-2-3392'>\n\t\t\t\tSortie des caves.\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/17-04-20-demenagement-16-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-04-20-d\u00e9m\u00e9nagement-16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-3394\" srcset=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-04-20-d\u00e9m\u00e9nagement-16-150x150.jpg 150w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-04-20-d\u00e9m\u00e9nagement-16-63x63.jpg 63w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-2-3394'>\n\t\t\t\tEn route vers la galerie\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/olympus-digital-camera-5-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-03-17-d\u00e9m-g\u00e9ants-8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-3386\" srcset=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-03-17-d\u00e9m-g\u00e9ants-8-150x150.jpg 150w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-03-17-d\u00e9m-g\u00e9ants-8-63x63.jpg 63w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-2-3386'>\n\t\t\t\tEntr\u00e9e en cave\n\t\t\t\t<\/dd><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Nous avons obtenu, un h\u00e9bergement provisoire de 4 semaines dans l\u2019\u00e9glise de la Chapelle pour nos 7 plus grands (et plus beaux) g\u00e9ants, Ob\u00e9lix et la Reine de l\u2019Eau se sont r\u00e9fugi\u00e9s au CC Bruegel.De l\u2019\u00e9glise de la Chapelle ils sont partis, le 17 mars, se r\u00e9fugier dans les caves de la Galerie Horta, f\u00eate de P\u00e2ques oblige,<br \/>\nMerci Monsieur Huerta\u00a0!<\/p>\n\n\t\t<style>\n\t\t\t#gallery-3 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-3 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-3' class='gallery galleryid-3098 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/olympus-digital-camera-7-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-4-Huerta-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-3444\" srcset=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-4-Huerta-150x150.jpg 150w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-4-Huerta-24x24.jpg 24w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-4-Huerta-36x36.jpg 36w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-4-Huerta-48x48.jpg 48w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-4-Huerta-298x300.jpg 298w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-4-Huerta-63x63.jpg 63w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-4-Huerta.jpg 621w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-3-3444'>\n\t\t\t\tMessieurs Deschuytere et Huerta\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/2017-dem-avril-5-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-d\u00e9m-avril-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-3418\" srcset=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-d\u00e9m-avril-5-150x150.jpg 150w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-d\u00e9m-avril-5-63x63.jpg 63w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-3-3418'>\n\t\t\t\tOb\u00e9lix et nos grandes dames en cave.\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/olympus-digital-camera-2-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-03-17-d\u00e9m-g\u00e9ants-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-3380\" srcset=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-03-17-d\u00e9m-g\u00e9ants-5-150x150.jpg 150w, https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/17-03-17-d\u00e9m-g\u00e9ants-5-63x63.jpg 63w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-3-3380'>\n\t\t\t\tMarion et Isabelle en cave\n\t\t\t\t<\/dd><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Un espace totalement surprenant, situ\u00e9 derri\u00e8re un m\u00e9ga stroumpf albinos, une galerie totalement vide de magasins, des couloirs et des caves dignes des catacombes&#8230;<br \/>\nUne entr\u00e9e avec porte s\u00e9curis\u00e9e en haut de la place Agora permet l\u2019acc\u00e8s arri\u00e8re \u00e0 ces espaces.<br \/>\nLe promoteur esp\u00e8re y r\u00e9aliser un mus\u00e9e \u00ab\u00a0historique\u00a0\u00bb\u00a0de la Grand-Place avec animations post-modernes vari\u00e9es (casque 3D, projections avec mouvements&#8230;) il lui manque (juste) un ou deux investisseurs et la suppression du droit de passage SNCB&#8230;<\/p>\n<p>Deux ans de d\u00e9lai pr\u00e9vu.<br \/>\nEt de r\u00e9pit\u00a0pour nos g\u00e9ants!<\/p>\n<p>Ils y ont \u00e9t\u00e9 rejoints par Ob\u00e9lix et la Reine de l\u2019Eau le 30 mars 2017.<br \/>\nNos dames et Ob\u00e9lix, si beau, si grand, mais si envelopp\u00e9 sont rest\u00e9s dans le couloir d\u2019acc\u00e8s jusqu\u2019au 20 avril\u00a0pour \u00e9vacuer, sous la pression des pompiers , dans la galerie pour les unes et de retour, provisoirement, rue des Renards dans l\u2019entr\u00e9e du centre Culturel Bruegel pour\u00a0notre gaulois pour lequel nous cherchons, toujours un abri pour l\u2019hiver&#8230;.<\/p>\n<p>Le service urbanisme de la Ville a mis \u00e0 notre disposition 50m2 sous une hauteur de 5m, nous avons pu y installer les autres g\u00e9ants et le mat\u00e9riel folklorique (g\u00e9ants en cours de restauration&#8230;), gr\u00e2ce \u00e0 Robert Dekock (Bon Repos)\u00a0et Carine Verstraeten (SIBP), les transports (\u00e0 Haren&#8230;) ont \u00e9t\u00e9 organis\u00e9s par le service voirie<\/p>\n<p>Nous cherchons, d\u2019autre part, un lieu pour les stocker \u00e0 moyen et long terme (leur refuge actuel, peu pratique dans les caves de la galerie Horta, sera indisponible dans 18 mois) ainsi que l\u2019ensemble de notre fonds folklorique ( grands g\u00e9ants\u00a0: Don Quichotte, petits g\u00e9ants\u00a0: Sophie et Gaston, g\u00e9ants en r\u00e9fection, Dona Isabella, Kwibe Kwibus, Rolle, Tapir, Ast\u00e9rix, Agent 15, Toots, Prolo des Marolles, tous stock\u00e9 \u00e0 Haren dans un d\u00e9p\u00f4t de la Ville, et indisponibles cette ann\u00e9e), Ob\u00e9lix que nous ne savons ou mettre depuis f\u00e9vrier, a \u00e9t\u00e9 entrepos\u00e9 devant le CC Bruegel jusqu&#8217;aux f\u00eates de Bruegel et des Saltimbanques de septembre, puis d\u00e9coup\u00e9 pour entrer, lui aussi, dans les caves de la galerie Horta&#8230;<\/p>\n<h3>Voir aussi le dossier :\u00a0\u00a0<a href=\"https:\/\/marolles.brussels\/2018\/06\/13\/la-famille-des-geants-du-quartier-bruegel-rue-haute-bruxelles\/\">&#8220;La Famille des g\u00e9ants du quartier Bruegel&#8221;<\/a><\/h3>\n<h3><a href=\"https:\/\/marolles.brussels\/2018\/06\/13\/2018-apres-une-pause-les-geants-demenagent-a-nouveau\/\">Et\u00a0 les aventures de nos g\u00e9ants en 2018 !\u00a0<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>MEUBLIA, une institution du quartier a \u00e9t\u00e9 d\u00e9finitivement ferm\u00e9, en f\u00e9vrier 2017, apr\u00e8s plus de 50 ans d\u2019existence. D&#8217;une ancienne distillerie du XIXe devenue une salle de danse au d\u00e9but [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":3370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[274,272],"tags":[333],"class_list":["post-3098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buurt","category-laatste-publicaties","tag-news-nl"],"acf":[],"cubewp_post_meta":[],"taxonomies":["Buurt","Laatste Publicaties","News"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute... - Marolles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute... - Marolles\" \/>\n<meta property=\"og:description\" content=\"MEUBLIA, une institution du quartier a \u00e9t\u00e9 d\u00e9finitivement ferm\u00e9, en f\u00e9vrier 2017, apr\u00e8s plus de 50 ans d\u2019existence. D&#8217;une ancienne distillerie du XIXe devenue une salle de danse au d\u00e9but [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/\" \/>\n<meta property=\"og:site_name\" content=\"Marolles\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-03T17:16:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-10T16:12:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"831\" \/>\n\t<meta property=\"og:image:height\" content=\"948\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comm_Marolles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/\"},\"author\":{\"name\":\"Comm_Marolles\",\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/#\\\/schema\\\/person\\\/9081ef0335393afa96ded2d689f118e8\"},\"headline\":\"2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute&#8230;\",\"datePublished\":\"2018-03-03T17:16:30+00:00\",\"dateModified\":\"2018-08-10T16:12:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/\"},\"wordCount\":689,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marolles.brussels\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/2017-D\u00e9m-avril-1.jpg\",\"keywords\":[\"News\"],\"articleSection\":[\"Buurt\",\"Laatste Publicaties\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/\",\"url\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/\",\"name\":\"2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute... - Marolles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marolles.brussels\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/2017-D\u00e9m-avril-1.jpg\",\"datePublished\":\"2018-03-03T17:16:30+00:00\",\"dateModified\":\"2018-08-10T16:12:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/#\\\/schema\\\/person\\\/9081ef0335393afa96ded2d689f118e8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marolles.brussels\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/2017-D\u00e9m-avril-1.jpg\",\"contentUrl\":\"https:\\\/\\\/marolles.brussels\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/2017-D\u00e9m-avril-1.jpg\",\"width\":831,\"height\":948},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/\",\"name\":\"Marolles\",\"description\":\"D\u00e9couvrez les meilleurs endroits pour manger, boire un verre entre amis ou faire vos achats pr\u00e8s de chez vous.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marolles.brussels\\\/nl\\\/#\\\/schema\\\/person\\\/9081ef0335393afa96ded2d689f118e8\",\"name\":\"Comm_Marolles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bc5d99950c5051e982ac0ce5695ba351fdea8320d86b1f40640c324699de114?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bc5d99950c5051e982ac0ce5695ba351fdea8320d86b1f40640c324699de114?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7bc5d99950c5051e982ac0ce5695ba351fdea8320d86b1f40640c324699de114?s=96&d=mm&r=g\",\"caption\":\"Comm_Marolles\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute... - Marolles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/","og_locale":"nl_NL","og_type":"article","og_title":"2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute... - Marolles","og_description":"MEUBLIA, une institution du quartier a \u00e9t\u00e9 d\u00e9finitivement ferm\u00e9, en f\u00e9vrier 2017, apr\u00e8s plus de 50 ans d\u2019existence. D&#8217;une ancienne distillerie du XIXe devenue une salle de danse au d\u00e9but [&hellip;]","og_url":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/","og_site_name":"Marolles","article_published_time":"2018-03-03T17:16:30+00:00","article_modified_time":"2018-08-10T16:12:33+00:00","og_image":[{"width":831,"height":948,"url":"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-1.jpg","type":"image\/jpeg"}],"author":"Comm_Marolles","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/#article","isPartOf":{"@id":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/"},"author":{"name":"Comm_Marolles","@id":"https:\/\/marolles.brussels\/nl\/#\/schema\/person\/9081ef0335393afa96ded2d689f118e8"},"headline":"2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute&#8230;","datePublished":"2018-03-03T17:16:30+00:00","dateModified":"2018-08-10T16:12:33+00:00","mainEntityOfPage":{"@id":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/"},"wordCount":689,"commentCount":0,"image":{"@id":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/#primaryimage"},"thumbnailUrl":"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-1.jpg","keywords":["News"],"articleSection":["Buurt","Laatste Publicaties"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/","url":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/","name":"2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute... - Marolles","isPartOf":{"@id":"https:\/\/marolles.brussels\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/#primaryimage"},"image":{"@id":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/#primaryimage"},"thumbnailUrl":"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-1.jpg","datePublished":"2018-03-03T17:16:30+00:00","dateModified":"2018-08-10T16:12:33+00:00","author":{"@id":"https:\/\/marolles.brussels\/nl\/#\/schema\/person\/9081ef0335393afa96ded2d689f118e8"},"breadcrumb":{"@id":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/#primaryimage","url":"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-1.jpg","contentUrl":"https:\/\/marolles.brussels\/wp-content\/uploads\/2017\/12\/2017-D\u00e9m-avril-1.jpg","width":831,"height":948},{"@type":"BreadcrumbList","@id":"https:\/\/marolles.brussels\/nl\/2017-annee-de-fuite-dabris-en-refuge-pour-les-geants-de-la-rue-haute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/marolles.brussels\/nl\/"},{"@type":"ListItem","position":2,"name":"2017, ann\u00e9e de fuite, d\u2019abris en refuge pour les g\u00e9ants de la rue Haute&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/marolles.brussels\/nl\/#website","url":"https:\/\/marolles.brussels\/nl\/","name":"Marolles","description":"D\u00e9couvrez les meilleurs endroits pour manger, boire un verre entre amis ou faire vos achats pr\u00e8s de chez vous.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marolles.brussels\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/marolles.brussels\/nl\/#\/schema\/person\/9081ef0335393afa96ded2d689f118e8","name":"Comm_Marolles","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/7bc5d99950c5051e982ac0ce5695ba351fdea8320d86b1f40640c324699de114?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7bc5d99950c5051e982ac0ce5695ba351fdea8320d86b1f40640c324699de114?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7bc5d99950c5051e982ac0ce5695ba351fdea8320d86b1f40640c324699de114?s=96&d=mm&r=g","caption":"Comm_Marolles"}}]}},"_links":{"self":[{"href":"https:\/\/marolles.brussels\/nl\/wp-json\/wp\/v2\/posts\/3098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marolles.brussels\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marolles.brussels\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marolles.brussels\/nl\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/marolles.brussels\/nl\/wp-json\/wp\/v2\/comments?post=3098"}],"version-history":[{"count":0,"href":"https:\/\/marolles.brussels\/nl\/wp-json\/wp\/v2\/posts\/3098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marolles.brussels\/nl\/wp-json\/wp\/v2\/media\/3370"}],"wp:attachment":[{"href":"https:\/\/marolles.brussels\/nl\/wp-json\/wp\/v2\/media?parent=3098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marolles.brussels\/nl\/wp-json\/wp\/v2\/categories?post=3098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marolles.brussels\/nl\/wp-json\/wp\/v2\/tags?post=3098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}